{"id":16,"count":5,"description":"","link":"https:\/\/portalsalud.es\/en\/category\/salud-mental\/","name":"Salud Mental","slug":"salud-mental","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salud Mental archivos - Portal Salud<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portalsalud.es\/en\/category\/salud-mental\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salud Mental archivos - Portal Salud\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portalsalud.es\/en\/category\/salud-mental\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal Salud\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portalsalud.es\/wp-content\/uploads\/2026\/03\/logo-PortalSalud.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/portalsalud.es\\\/category\\\/salud-mental\\\/\",\"url\":\"https:\\\/\\\/portalsalud.es\\\/category\\\/salud-mental\\\/\",\"name\":\"Salud Mental archivos - Portal Salud\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portalsalud.es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/portalsalud.es\\\/category\\\/salud-mental\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/portalsalud.es\\\/category\\\/salud-mental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/portalsalud.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salud Mental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/portalsalud.es\\\/#website\",\"url\":\"https:\\\/\\\/portalsalud.es\\\/\",\"name\":\"Portal Salud\",\"description\":\"Tu aliado diario para una vida m&aacute;s sana. En PortalSalud compartimos consejos pr&aacute;cticos sobre nutrici&oacute;n, salud mental y h&aacute;bitos saludables para que alcances tu mejor versi&oacute;n de forma equilibrada y natural.\",\"publisher\":{\"@id\":\"https:\\\/\\\/portalsalud.es\\\/#organization\"},\"alternateName\":\"PortalSalud\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/portalsalud.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/portalsalud.es\\\/#organization\",\"name\":\"Portal Salud\",\"alternateName\":\"PortalSalud\",\"url\":\"https:\\\/\\\/portalsalud.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/portalsalud.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/portalsalud.es\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cropped-logo-PortalSalud2.png\",\"contentUrl\":\"https:\\\/\\\/portalsalud.es\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cropped-logo-PortalSalud2.png\",\"width\":512,\"height\":512,\"caption\":\"Portal Salud\"},\"image\":{\"@id\":\"https:\\\/\\\/portalsalud.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/virallab2411\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@virallab2411\",\"https:\\\/\\\/www.youtube.com\\\/@ViralLabPortalSalud\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salud Mental archivos - Portal Salud","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portalsalud.es\/en\/category\/salud-mental\/","og_locale":"en_US","og_type":"article","og_title":"Salud Mental archivos - Portal Salud","og_url":"https:\/\/portalsalud.es\/en\/category\/salud-mental\/","og_site_name":"Portal Salud","og_image":[{"width":1536,"height":1024,"url":"https:\/\/portalsalud.es\/wp-content\/uploads\/2026\/03\/logo-PortalSalud.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/portalsalud.es\/category\/salud-mental\/","url":"https:\/\/portalsalud.es\/category\/salud-mental\/","name":"Salud Mental archivos - Portal Salud","isPartOf":{"@id":"https:\/\/portalsalud.es\/#website"},"breadcrumb":{"@id":"https:\/\/portalsalud.es\/category\/salud-mental\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/portalsalud.es\/category\/salud-mental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/portalsalud.es\/"},{"@type":"ListItem","position":2,"name":"Salud Mental"}]},{"@type":"WebSite","@id":"https:\/\/portalsalud.es\/#website","url":"https:\/\/portalsalud.es\/","name":"Portal Salud","description":"Tu aliado diario para una vida m&aacute;s sana. En PortalSalud compartimos consejos pr&aacute;cticos sobre nutrici&oacute;n, salud mental y h&aacute;bitos saludables para que alcances tu mejor versi&oacute;n de forma equilibrada y natural.","publisher":{"@id":"https:\/\/portalsalud.es\/#organization"},"alternateName":"PortalSalud","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portalsalud.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/portalsalud.es\/#organization","name":"Portal Salud","alternateName":"PortalSalud","url":"https:\/\/portalsalud.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/portalsalud.es\/#\/schema\/logo\/image\/","url":"https:\/\/portalsalud.es\/wp-content\/uploads\/2026\/04\/cropped-logo-PortalSalud2.png","contentUrl":"https:\/\/portalsalud.es\/wp-content\/uploads\/2026\/04\/cropped-logo-PortalSalud2.png","width":512,"height":512,"caption":"Portal Salud"},"image":{"@id":"https:\/\/portalsalud.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/virallab2411\/","https:\/\/www.tiktok.com\/@virallab2411","https:\/\/www.youtube.com\/@ViralLabPortalSalud"]}]}},"_links":{"self":[{"href":"https:\/\/portalsalud.es\/en\/wp-json\/wp\/v2\/categories\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portalsalud.es\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/portalsalud.es\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/portalsalud.es\/en\/wp-json\/wp\/v2\/posts?categories=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}